{"id":15369,"date":"2020-08-05T10:00:36","date_gmt":"2020-08-05T09:00:36","guid":{"rendered":"https:\/\/sd-memory-cards.net\/?p=15369"},"modified":"2024-02-16T16:08:59","modified_gmt":"2024-02-16T16:08:59","slug":"sandisk-ultra","status":"publish","type":"post","link":"https:\/\/sd-memory-cards.net\/it\/sandisk-ultra\/","title":{"rendered":"SanDisk Ultra microSDXC Full Review (64GB-512GB)"},"content":{"rendered":"<p>SanDisk occupa i primi 3 posti nella classifica delle unit\u00e0 SD Card pi\u00f9 vendute su Amazon. Offrono un <strong>ampia scelta di schede di memoria<\/strong> che si rivolge a diversi tipi di utenti. SanDisk ha un'ottima immagine per le sue SD Card durevoli e affidabili. Quindi, se si chiede ai possessori di fotocamere quale SD Card utilizzano o quale sia la migliore marca di schede, si sente spesso dire<strong> SanDisk<\/strong>.<\/p>\n<p>La scheda di memoria pi\u00f9 venduta sul sito web di Amazon \u00e8 la scheda <strong>SanDisk Ultra<\/strong>. \u00c8 una scheda che offre un prezzo ragionevole e non manca di prestazioni. La variante da 64 GB, in particolare, ha pi\u00f9 di 200 mila valutazioni da parte dei clienti su Amazon, con 84% dei clienti che valutano la scheda con cinque stelle.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-15382\" src=\"https:\/\/sd-memory-cards.net\/wp-content\/themes\/reco\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-956x1024.jpg\" alt=\"\" width=\"358\" height=\"383\" srcset=\"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-956x1024.jpg 956w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-280x300.jpg 280w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-768x822.jpg 768w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-1080x1156.jpg 1080w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-93x100.jpg 93w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-420x450.jpg 420w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_-1121x1200.jpg 1121w, https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/05\/71uzc4PDmSL._AC_SL1500_.jpg 1356w\" sizes=\"(max-width: 358px) 100vw, 358px\" \/><\/p>\n<p><strong>200.000 clienti<\/strong> non sono uno scherzo. Questo dimostra quanto valore offra la SanDisk Ultra considerando il suo prezzo. Ora, per saperne di pi\u00f9 sulla scheda, vediamo alcune specifiche tecniche.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><b>Sandisk Ultra: Specifiche<\/b><\/h2>\n<hr \/>\n<p>La variante da 64 GB del<strong> SanDisk Ultra<\/strong> ha un prezzo inferiore a $20. Ha una velocit\u00e0 di trasferimento fino a 100 MB al secondo e prestazioni classificate A1 per le applicazioni di caricamento.<\/p>\n<p><span style=\"font-weight: 400;\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal\"  data-aawp-product-id=\"B074RNRM2B\" data-aawp-product-title=\"SanDisk 400GB Ultra MicroSDXC UHS-I Memory Card with Adapter - 100MB\/s C10 U1 Full HD A1 Micro SD Card - SDSQUAR-400G-GN6MA\" data-aawp-geotargeting=\"true\" data-aawp-click-tracking=\"title\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/sd-memory-cards.net\/wp-content\/themes\/reco\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/m.media-amazon.com\/images\/I\/417NhhsEBeL.jpg\" alt=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            SanDisk 400GB Ultra MicroSDXC UHS-I...        <\/a>\n        <div class=\"aawp-product__description\">\n            <ul><li>Ideale per smartphone e tablet Android e fotocamere MIL<\/li><li>Capacit\u00e0 fino a 512GB (1GB=1.000.000.000 di byte. La memoria effettiva dell'utente \u00e8 inferiore) per memorizzare...<\/li><li>Velocit\u00e0 di trasferimento in lettura fino a 100MB\/s (in base a test interni; le prestazioni possono...<\/li><\/ul>        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--amazon shadow aawp-button--icon aawp-button--icon-amazon-black\" href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Controlla il prezzo su Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Controlla il prezzo su Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><b>Prestazioni della scheda di memoria<\/b><\/h2>\n<hr \/>\n<p>Le schede di memoria SanDisk sono note per le loro ottime prestazioni. \u00c8 il marchio preferito dagli utenti di fotocamere comuni e dalla maggior parte dei fotografi professionisti.<\/p>\n<p>Dal punto di vista tecnico, vediamo come si comportano le velocit\u00e0 di lettura e scrittura della SanDisk Ultra.<\/p>\n<h3><b>Velocit\u00e0 di scrittura<\/b><\/h3>\n<p>La velocit\u00e0 di scrittura della memoria identifica la capacit\u00e0 di un SD Card di memorizzare informazioni dalla fotocamera a una determinata velocit\u00e0. Ad esempio, una videocamera GoPro con una <strong>Impostazione video 4k 60 FPS<\/strong> deve trasferire i dati all'SD Card ad una velocit\u00e0 di <strong>7,5 MB al secondo<\/strong>. Pertanto, se si tenta di registrare video 4k su un SD Card con velocit\u00e0 di scrittura inferiori a 7,5 MB al secondo, si verificheranno errori dell'SD Card e la videocamera si bloccher\u00e0.<\/p>\n<p>Non si vuole essere la persona con una fotocamera che si perde ogni momento di un evento perch\u00e9 la sua SD Card continua a non funzionare. In questo caso, prima di acquistare una scheda di memoria, \u00e8 necessario valutarne la velocit\u00e0 di scrittura.<\/p>\n<p>Il <strong>SanDisk Ultra<\/strong> ha una velocit\u00e0 di scrittura fino a 10 MB al secondo, che \u00e8 un po' lenta. Ma, considerando il prezzo, non ci si pu\u00f2 lamentare pi\u00f9 di tanto.<\/p>\n<p>Date un'occhiata ai numeri sulle prestazioni di SanDisk Ultra da <em>Velocit\u00e0 della memoria della fotocamera<\/em><\/p>\n\n<table id=\"tablepress-82\" class=\"tablepress tablepress-id-82\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SanDisk Ultra<\/th><th class=\"column-2\">Seq. Scrittura 1000MB MB\/s<\/th><th class=\"column-3\">Rand. Scrivere 512KB MB\/s<\/th><th class=\"column-4\">Rand. Scrivere 4KB MB\/s QD1<\/th><th class=\"column-5\">Rand. Scrittura 4KB IOPS QD1<\/th><th class=\"column-6\">Rand. Scrivere 4KB MB\/s QD32<\/th><th class=\"column-7\">Rand. Scrittura 4KB IOPS QD32<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Lettore di schede SanDisk UHS-1<\/td><td class=\"column-2\">65.789<\/td><td class=\"column-3\">21.829<\/td><td class=\"column-4\">1.399<\/td><td class=\"column-5\">365.7<\/td><td class=\"column-6\">1.537<\/td><td class=\"column-7\">419.4<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Lettore Hama USB 3.0 SD Card<\/td><td class=\"column-2\">69.895<\/td><td class=\"column-3\">30.213<\/td><td class=\"column-4\">2.326<\/td><td class=\"column-5\">311.9<\/td><td class=\"column-6\">2.328<\/td><td class=\"column-7\">512.5<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Lettore di schede Lexar Professional SR2<\/td><td class=\"column-2\">67.055<\/td><td class=\"column-3\">29.818<\/td><td class=\"column-4\">1.274<\/td><td class=\"column-5\">599.2<\/td><td class=\"column-6\">2.275<\/td><td class=\"column-7\">599.5<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Lettore SanDisk Extreme Pro SD<\/td><td class=\"column-2\">67.468<\/td><td class=\"column-3\">28.967<\/td><td class=\"column-4\">1.469<\/td><td class=\"column-5\">402.8<\/td><td class=\"column-6\">1.634<\/td><td class=\"column-7\">443.0<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Lettore di schede Hama USB Tipo-C 3.1<\/td><td class=\"column-2\">67.644<\/td><td class=\"column-3\">30.014<\/td><td class=\"column-4\">2.313<\/td><td class=\"column-5\">508.9<\/td><td class=\"column-6\">2337<\/td><td class=\"column-7\">514.8<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Lettore UHS-II ad alta velocit\u00e0 Sony S1<\/td><td class=\"column-2\">67.113<\/td><td class=\"column-3\">28.771<\/td><td class=\"column-4\">1.430<\/td><td class=\"column-5\">393.3<\/td><td class=\"column-6\">1.518<\/td><td class=\"column-7\">414.7<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-82 from cache -->\n<h3><b>Velocit\u00e0 di lettura<\/b><\/h3>\n<p>Dopo aver utilizzato la fotocamera per registrare video e scattare foto, \u00e8 probabile che si vogliano trasferire i file sul computer. \u00c8 qui che la velocit\u00e0 di lettura della memoria \u00e8 importante. La velocit\u00e0 di lettura identifica la<strong> velocit\u00e0 di trasferimento dei file<\/strong> che un SD Card pu\u00f2 gestire durante la copia dei file su un computer o su un altro dispositivo di memorizzazione.<\/p>\n<p>Il trasferimento di file di grandi dimensioni pu\u00f2 richiedere del tempo, soprattutto se si tratta di trasferire file di dimensioni pari o superiori a 20 GB. Potreste ritrovarvi a fissare il computer per ore in attesa che il trasferimento dei file finisca.<\/p>\n<p><strong>SanDisk Ultra<\/strong> ha una velocit\u00e0 di lettura fino a <strong>80 MB al secondo<\/strong> che \u00e8 decente se si considera il suo prezzo. Questo \u00e8 anche il motivo per cui le schede di memoria SanDisk sono fantastiche. Offrono prestazioni complete su tutte le loro schede a un prezzo decente. Alcune marche possono essere pi\u00f9 economiche rispetto ai modelli SanDisk, ma quando si d\u00e0 un'occhiata alle specifiche tecniche, queste schede hanno spesso velocit\u00e0 di lettura ridotte.<\/p>\n<p>Date un'occhiata ad alcuni risultati dei benchmark di Camera Memory Speed<\/p>\n\n<table id=\"tablepress-83\" class=\"tablepress tablepress-id-83\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SanDisk Ultra<\/th><th class=\"column-2\">Seq. Lettura 1000MB MB\/s<\/th><th class=\"column-3\">Rand. Lettura 512KB MB\/s<\/th><th class=\"column-4\">Rand. Lettura 4KB MB\/s QD1<\/th><th class=\"column-5\">Rand. Lettura 4KB IOPS QD1<\/th><th class=\"column-6\">Rand. Lettura 4KB MB\/s QD32<\/th><th class=\"column-7\">Rand. Lettura 4KB IOPS QD32<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Lettore di schede SanDisk UHS-1<\/td><td class=\"column-2\">100.987<\/td><td class=\"column-3\">95.663<\/td><td class=\"column-4\">2.545<\/td><td class=\"column-5\">765.4<\/td><td class=\"column-6\">2.790<\/td><td class=\"column-7\">869.2<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Lettore Hama USB 3.0 SD Card<\/td><td class=\"column-2\">88.269<\/td><td class=\"column-3\">81.046<\/td><td class=\"column-4\">3.685<\/td><td class=\"column-5\">1187.8<\/td><td class=\"column-6\">3.857<\/td><td class=\"column-7\">1229.9<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Lettore di schede Lexar Professional SR2<\/td><td class=\"column-2\">88.269<\/td><td class=\"column-3\">80.831<\/td><td class=\"column-4\">3.730<\/td><td class=\"column-5\">1198.9<\/td><td class=\"column-6\">3.857<\/td><td class=\"column-7\">1229.9<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Lettore Lexar LRWM04U-7000 UHS-II<\/td><td class=\"column-2\">88.259<\/td><td class=\"column-3\">70.164<\/td><td class=\"column-4\">3.683<\/td><td class=\"column-5\">1187.4<\/td><td class=\"column-6\">3.843<\/td><td class=\"column-7\">1226.6<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Lettore di schede Hama USB Tipo-C 3.1<\/td><td class=\"column-2\">89.978<\/td><td class=\"column-3\">70.044<\/td><td class=\"column-4\">3.888<\/td><td class=\"column-5\">1137.6<\/td><td class=\"column-6\">3.884<\/td><td class=\"column-7\">1236.5<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Lettore\/Scrittore SanDisk Extreme Pro SD UHS-II\t<\/td><td class=\"column-2\">89.969<\/td><td class=\"column-3\">72.349<\/td><td class=\"column-4\">2.501<\/td><td class=\"column-5\">998.9<\/td><td class=\"column-6\">2.904<\/td><td class=\"column-7\">1097.2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-83 from cache -->\n<h3><b>Test di velocit\u00e0<\/b><\/h3>\n<p>Questo test di velocit\u00e0 mostra le prestazioni di una scheda Sandisk Ultra 128GB Micro SDXC UHS-I con adattatore - 100MB\/s U1 A1 - SDSQUAR-128G-GN6MA testata con CrystalMark.<\/p>\n<p><iframe title=\"SanDisk Ultra 128GB microSDXC SDSQUAR-128G-GN6MA Unboxing + Speed Test\" width=\"719\" height=\"404\" src=\"https:\/\/sd-memory-cards.net\/wp-content\/themes\/reco\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/www.youtube.com\/embed\/DyF4qdgd3bY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h3><b>Dimensioni della scheda di memoria<\/b><\/h3>\n<p>\u00c8 possibile ottenere il <strong>SanDisk Ultra<\/strong> in:<\/p>\n<ul>\n<li><strong>32 GB<\/strong><\/li>\n<li><strong>64 GB<\/strong><\/li>\n<li><strong>128 GB<\/strong><\/li>\n<li><strong>200 GB<\/strong><\/li>\n<li><strong>256 GB<\/strong><\/li>\n<li><strong>400 GB<\/strong><\/li>\n<li><strong>512 GB<\/strong><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal\"  data-aawp-product-id=\"B074RNRM2B\" data-aawp-product-title=\"SanDisk 400GB Ultra MicroSDXC UHS-I Memory Card with Adapter - 100MB\/s C10 U1 Full HD A1 Micro SD Card - SDSQUAR-400G-GN6MA\" data-aawp-geotargeting=\"true\" data-aawp-click-tracking=\"title\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/sd-memory-cards.net\/wp-content\/themes\/reco\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/m.media-amazon.com\/images\/I\/417NhhsEBeL.jpg\" alt=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            SanDisk 400GB Ultra MicroSDXC UHS-I...        <\/a>\n        <div class=\"aawp-product__description\">\n            <ul><li>Ideale per smartphone e tablet Android e fotocamere MIL<\/li><li>Capacit\u00e0 fino a 512GB (1GB=1.000.000.000 di byte. La memoria effettiva dell'utente \u00e8 inferiore) per memorizzare...<\/li><li>Velocit\u00e0 di trasferimento in lettura fino a 100MB\/s (in base a test interni; le prestazioni possono...<\/li><\/ul>        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--amazon shadow aawp-button--icon aawp-button--icon-amazon-black\" href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Controlla il prezzo su Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Controlla il prezzo su Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><b>Dispositivi che funzionano bene con Sandisk Ultra<\/b><\/h2>\n<hr \/>\n<p>Il pi\u00f9 delle volte, <a href=\"https:\/\/amzn.to\/3fUSSjW\" target=\"_blank\" rel=\"noopener noreferrer\">Schede di memoria SanDisk<\/a> funzioner\u00e0 senza problemi sulla maggior parte dei dispositivi che supportano l'espansione SD Card. Per essere pi\u00f9 precisi, \u00e8 possibile controllare l'elenco di seguito riportato per verificare la compatibilit\u00e0 della SanDisk Ultra.<\/p>\n<ul>\n<li><strong>Smartphone<\/strong> - Gli smartphone non richiedono velocit\u00e0 di lettura e scrittura folli sulle schede SD per funzionare. La SanDisk ultra funziona su qualsiasi smartphone che supporti l'espansione di memoria. \u00c8 ottima per salvare giochi, foto, musica e video.<\/li>\n<li><strong>Telecamere da cruscotto<\/strong> - Con l'aumento dei proprietari di auto che acquistano dash cam per la protezione, aumenta anche la necessit\u00e0 di schede SD. Se siete alla ricerca di una scheda di memoria economica da utilizzare per le vostre dashcam, la SanDisk Ultra \u00e8 l'ideale. Dato che la maggior parte delle dashcam non richiede velocit\u00e0 di lettura e scrittura elevate e spesso registra video a 1080P o a risoluzioni inferiori, il modello Ultra \u00e8 sicuramente in grado di gestire perfettamente le registrazioni della vostra dashcam.<\/li>\n<li><strong>Console portatili<\/strong> - Le console come la Playstation Portable e la pi\u00f9 recente Nintendo Switch utilizzano gli SD Card per salvare i giochi. La SanDisk Ultra ha una discreta velocit\u00e0 di lettura, importante per velocizzare il caricamento dei giochi sulla console.<\/li>\n<li><strong>Telecamere<\/strong> - Sebbene alcune videocamere richiedano velocit\u00e0 di scrittura elevate per la registrazione di video in 4k, SanDisk Ultra \u00e8 comunque in grado di gestire le impostazioni video a 1080P su qualsiasi videocamera professionale. Se non desiderate registrare video in 4k sulla vostra fotocamera o se la vostra fotocamera non supporta la registrazione video in 4k, l'acquisto della SanDisk Ultra pu\u00f2 essere un'ottima opzione in termini di budget.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><b>Dovreste acquistare una Sandisk Ultra per la vostra fotocamera?<\/b><\/h2>\n<hr \/>\n<p>Per rispondere a questa domanda, \u00e8 necessario considerare un paio di aspetti se si sta pensando di acquistare il<strong> SanDisk Ultra<\/strong> per la vostra fotocamera. Se si possiede una fotocamera che <strong>non supporta la registrazione video 4k<\/strong> o non volete girare video a risoluzione 4k, allora potete prendere in considerazione l'acquisto della SanDisk Ultra.<\/p>\n<p><span style=\"font-weight: 400;\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal\"  data-aawp-product-id=\"B074RNRM2B\" data-aawp-product-title=\"SanDisk 400GB Ultra MicroSDXC UHS-I Memory Card with Adapter - 100MB\/s C10 U1 Full HD A1 Micro SD Card - SDSQUAR-400G-GN6MA\" data-aawp-geotargeting=\"true\" data-aawp-click-tracking=\"title\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/sd-memory-cards.net\/wp-content\/themes\/reco\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/m.media-amazon.com\/images\/I\/417NhhsEBeL.jpg\" alt=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 400GB Ultra MicroSDXC UHS-I...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            SanDisk 400GB Ultra MicroSDXC UHS-I...        <\/a>\n        <div class=\"aawp-product__description\">\n            <ul><li>Ideale per smartphone e tablet Android e fotocamere MIL<\/li><li>Capacit\u00e0 fino a 512GB (1GB=1.000.000.000 di byte. La memoria effettiva dell'utente \u00e8 inferiore) per memorizzare...<\/li><li>Velocit\u00e0 di trasferimento in lettura fino a 100MB\/s (in base a test interni; le prestazioni possono...<\/li><\/ul>        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--amazon shadow aawp-button--icon aawp-button--icon-amazon-black\" href=\"https:\/\/www.amazon.com\/dp\/B074RNRM2B?tag=sdmemorycard05-20&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Controlla il prezzo su Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Controlla il prezzo su Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/span><\/p>\n<p>Ora, per il prezzo della SanDisk Ultra, si otterranno<strong> velocit\u00e0 di lettura e scrittura decenti<\/strong> con supporto per registrazioni video FHD. \u00c8 classificata come classe 10 con velocit\u00e0 di lettura fino a 80 MB al secondo. Ha una valutazione delle prestazioni A1 nelle applicazioni di caricamento e garantisce l'affidabilit\u00e0 e la durata del marchio SanDisk.<\/p>\n<p>Tuttavia, se siete un <strong>fotografo professionista<\/strong> questa scheda potrebbe non essere adatta alle vostre esigenze. Considerati gli standard odierni, i video in 4k sono necessari soprattutto per i professionisti. Ora, a volte \u00e8 possibile registrare video in 4k con la scheda <strong>SanDisk Ultra<\/strong> ma non \u00e8 il caso di sfidare la fortuna ogni volta che si girano video. Per le fotocamere di fascia alta \u00e8 consigliabile acquistare schede di memoria con velocit\u00e0 di lettura e scrittura pi\u00f9 elevate.<\/p>\n<p>Un'altra cosa da considerare \u00e8 che \u00e8 consigliabile ottenere almeno un<strong> SD Card con capacit\u00e0 di archiviazione di 64 GB<\/strong>. Con le moderne videocamere in grado di riprendere video a risoluzione 4k e superiore, anche le dimensioni dei file dei video aumentano.<\/p>\n<p>Ad esempio, una scheda di memoria da 32 GB consente di registrare 1 ora e mezza di video a 1080P e pi\u00f9 se si imposta la risoluzione a 1440P o 4k. Inoltre, la variante da 32 GB \u00e8 solo <strong>5 dollari in meno<\/strong> rispetto all'opzione di archiviazione da 64 GB, che corrisponde al doppio della capacit\u00e0 di archiviazione.<\/p>\n<p><strong>Potete anche considerare di acquistare il bundle da 128 GB + 64 GB di memoria su Amazon:<\/strong><\/p>\n<p><span style=\"font-weight: 400;\"><p >Nessun prodotto trovato.<\/p><\/span><\/p>\n<h4>Alternativa SD Card<\/h4>\n<p>Se siete un <strong>professionale<\/strong> chi \u00e8 alla ricerca di un'alternativa SD Card che non sia una rottura, pu\u00f2 provare a controllare il modello SanDisk Extreme. Ha una velocit\u00e0 di lettura di <strong>fino a 90 MB al secondo<\/strong> e <strong>velocit\u00e0 di scrittura di 40 MB<\/strong> al secondo. Dispone di diverse opzioni di archiviazione e ha una garanzia a vita del produttore.<\/p>\n<p><span style=\"font-weight: 400;\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal\"  data-aawp-product-id=\"B07FCR3316\" data-aawp-product-title=\"SanDisk 256GB Extreme microSDXC UHS-I Memory Card with Adapter - Up to 160MB\/s C10 U3 V30 4K A2 Micro SD - SDSQXA1-256G-GN6MA\" data-aawp-geotargeting=\"true\" data-aawp-click-tracking=\"title\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/www.amazon.com\/dp\/B07FCR3316?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 256GB Extreme microSDXC...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/sd-memory-cards.net\/wp-content\/themes\/reco\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/m.media-amazon.com\/images\/I\/41NKkAkE8iL.jpg\" alt=\"SanDisk 256GB Extreme microSDXC...\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.com\/dp\/B07FCR3316?tag=sdmemorycard05-20&linkCode=ogi&th=1&psc=1\" title=\"SanDisk 256GB Extreme microSDXC...\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            SanDisk 256GB Extreme microSDXC...        <\/a>\n        <div class=\"aawp-product__description\">\n            <ul><li>Velocit\u00e0 di lettura fino a 160 MB\/s per risparmiare tempo nel trasferimento di immagini ad alta...<\/li><li>Velocit\u00e0 di scrittura fino a 90MB\/s per scatti veloci; Richiede dispositivi compatibili in grado di...<\/li><li>4K UHD e Full HD Ready con UHS classe di velocit\u00e0 3 (U3) e classe di velocit\u00e0 video 30 (V30)<\/li><\/ul>        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--amazon shadow aawp-button--icon aawp-button--icon-amazon-black\" href=\"https:\/\/www.amazon.com\/dp\/B07FCR3316?tag=sdmemorycard05-20&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Controlla il prezzo su Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Controlla il prezzo su Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/span><\/p>\n<p><a href=\"https:\/\/sd-memory-cards.net\/sandisk-ultra-vs-extreme\/\" target=\"_blank\" rel=\"noopener noreferrer\">Clicca qui<\/a> per controllare il nostro <strong>confronto<\/strong> tra il <em>SanDisk Ultra<\/em> e <em>SanDisk Extreme<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h3 class=\"toolkit\"><strong>Articoli correlati:<\/strong><\/h3>\n<ul>\n<li><a href=\"https:\/\/sd-memory-cards.net\/samsung-evo-vs-sandisk-extreme\/\" target=\"_blank\" rel=\"noopener noreferrer\">Battaglia delle schede di memoria: Samsung Evo Plus vs SanDisk Extreme<\/a><\/li>\n<li><a href=\"https:\/\/sd-memory-cards.net\/best-sandisk-micro-sd-cards\/\" target=\"_blank\" rel=\"noopener noreferrer\">I 7 migliori Sandisk Micro SD Card (veloci)<\/a><\/li>\n<li><a href=\"https:\/\/sd-memory-cards.net\/best-sd-card-gopro-8\/\" target=\"_blank\" rel=\"noopener noreferrer\">8 migliori schede sd per la gopro hero 8 [consigliate da GoPro].<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/projectgo.pro\/best-memory-cards\/\" target=\"_blank\" rel=\"noopener noreferrer\">(torna alla pagina delle recensioni di SD Card)<\/a><\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>SanDisk owns the top 3 spots on Amazon&#8217;s best selling SD Card list. They offer a wide selection of memory card that caters to different&#8230;<\/p>","protected":false},"author":939,"featured_media":16129,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[51],"tags":[122,130,128],"class_list":["post-15369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memory-cards","tag-sandisk","tag-sd-card","tag-sd-card-reviews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.2.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SanDisk Ultra microSDXC Full Review (64GB\/128GB\/256GB..)<\/title>\n<meta name=\"description\" content=\"SanDisk Ultra SD Memory Card provides good performance for most cameras. Here&#039;s a review of this SD Card (Speed, Specs, Performance, Price)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sd-memory-cards.net\/it\/sandisk-ultra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SanDisk Ultra microSDXC Full Review (64GB-512GB)\" \/>\n<meta property=\"og:description\" content=\"SanDisk Ultra SD Memory Card provides good performance for most cameras. Here&#039;s a review of this SD Card (Speed, Specs, Performance, Price)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sd-memory-cards.net\/it\/sandisk-ultra\/\" \/>\n<meta property=\"og:site_name\" content=\"SD Memory Cards\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100068407795273\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-05T09:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T16:08:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/06\/sandisk-ultra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"725\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SD Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"SD Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/\"},\"author\":{\"name\":\"SD Team\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#\\\/schema\\\/person\\\/c682d19e914a27e7ad753c9a4dd6af17\"},\"headline\":\"SanDisk Ultra microSDXC Full Review (64GB-512GB)\",\"datePublished\":\"2020-08-05T09:00:36+00:00\",\"dateModified\":\"2024-02-16T16:08:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/\"},\"wordCount\":1296,\"publisher\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sd-memory-cards.net\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/sandisk-ultra.jpg\",\"keywords\":[\"sandisk\",\"sd card\",\"sd card reviews\"],\"articleSection\":[\"Memory Cards\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/\",\"url\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/\",\"name\":\"SanDisk Ultra microSDXC Full Review (64GB\\\/128GB\\\/256GB..)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sd-memory-cards.net\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/sandisk-ultra.jpg\",\"datePublished\":\"2020-08-05T09:00:36+00:00\",\"dateModified\":\"2024-02-16T16:08:59+00:00\",\"description\":\"SanDisk Ultra SD Memory Card provides good performance for most cameras. Here's a review of this SD Card (Speed, Specs, Performance, Price)\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/sandisk-ultra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sd-memory-cards.net\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/sandisk-ultra.jpg\",\"contentUrl\":\"https:\\\/\\\/sd-memory-cards.net\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/sandisk-ultra.jpg\",\"width\":725,\"height\":463,\"caption\":\"sandisk ultra\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#website\",\"url\":\"https:\\\/\\\/sd-memory-cards.net\\\/\",\"name\":\"SD Memory Cards\",\"description\":\"Everything about Memory Cards &amp; Storage Devices\",\"publisher\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sd-memory-cards.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#organization\",\"name\":\"SD Memory Cards\",\"url\":\"https:\\\/\\\/sd-memory-cards.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sd-memory-cards.net\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/sd-memory-cards-logo.png\",\"contentUrl\":\"https:\\\/\\\/sd-memory-cards.net\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/sd-memory-cards-logo.png\",\"width\":748,\"height\":148,\"caption\":\"SD Memory Cards\"},\"image\":{\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100068407795273\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sd-memory-cards.net\\\/#\\\/schema\\\/person\\\/c682d19e914a27e7ad753c9a4dd6af17\",\"name\":\"SD Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92c1bed94f5f72dd3a74aed94c1ef7f6a4fff2af9bcf7471e9124be460526205?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92c1bed94f5f72dd3a74aed94c1ef7f6a4fff2af9bcf7471e9124be460526205?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92c1bed94f5f72dd3a74aed94c1ef7f6a4fff2af9bcf7471e9124be460526205?s=96&d=mm&r=g\",\"caption\":\"SD Team\"},\"url\":\"https:\\\/\\\/sd-memory-cards.net\\\/it\\\/author\\\/sd-team\\\/\"},false]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/DyF4qdgd3bY\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"155\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:upload_date\" content=\"2020-08-05T09:00:36+00:00\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SanDisk Ultra microSDXC Full Review (64GB\/128GB\/256GB..)","description":"SanDisk Ultra SD Memory Card provides good performance for most cameras. Here's a review of this SD Card (Speed, Specs, Performance, Price)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sd-memory-cards.net\/it\/sandisk-ultra\/","og_locale":"it_IT","og_type":"article","og_title":"SanDisk Ultra microSDXC Full Review (64GB-512GB)","og_description":"SanDisk Ultra SD Memory Card provides good performance for most cameras. Here's a review of this SD Card (Speed, Specs, Performance, Price)","og_url":"https:\/\/sd-memory-cards.net\/it\/sandisk-ultra\/","og_site_name":"SD Memory Cards","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100068407795273","article_published_time":"2020-08-05T09:00:36+00:00","article_modified_time":"2024-02-16T16:08:59+00:00","og_image":[{"width":725,"height":463,"url":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/06\/sandisk-ultra.jpg","type":"image\/jpeg"}],"author":"SD Team","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"SD Team","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/#article","isPartOf":{"@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/"},"author":{"name":"SD Team","@id":"https:\/\/sd-memory-cards.net\/#\/schema\/person\/c682d19e914a27e7ad753c9a4dd6af17"},"headline":"SanDisk Ultra microSDXC Full Review (64GB-512GB)","datePublished":"2020-08-05T09:00:36+00:00","dateModified":"2024-02-16T16:08:59+00:00","mainEntityOfPage":{"@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/"},"wordCount":1296,"publisher":{"@id":"https:\/\/sd-memory-cards.net\/#organization"},"image":{"@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/#primaryimage"},"thumbnailUrl":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/06\/sandisk-ultra.jpg","keywords":["sandisk","sd card","sd card reviews"],"articleSection":["Memory Cards"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/","url":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/","name":"SanDisk Ultra microSDXC Full Review (64GB\/128GB\/256GB..)","isPartOf":{"@id":"https:\/\/sd-memory-cards.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/#primaryimage"},"image":{"@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/#primaryimage"},"thumbnailUrl":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/06\/sandisk-ultra.jpg","datePublished":"2020-08-05T09:00:36+00:00","dateModified":"2024-02-16T16:08:59+00:00","description":"SanDisk Ultra SD Memory Card provides good performance for most cameras. Here's a review of this SD Card (Speed, Specs, Performance, Price)","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sd-memory-cards.net\/sandisk-ultra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sd-memory-cards.net\/sandisk-ultra\/#primaryimage","url":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/06\/sandisk-ultra.jpg","contentUrl":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2020\/06\/sandisk-ultra.jpg","width":725,"height":463,"caption":"sandisk ultra"},{"@type":"WebSite","@id":"https:\/\/sd-memory-cards.net\/#website","url":"https:\/\/sd-memory-cards.net\/","name":"SD Memory Cards","description":"Everything about Memory Cards &amp; Storage Devices","publisher":{"@id":"https:\/\/sd-memory-cards.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sd-memory-cards.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sd-memory-cards.net\/#organization","name":"SD Memory Cards","url":"https:\/\/sd-memory-cards.net\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sd-memory-cards.net\/#\/schema\/logo\/image\/","url":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2022\/11\/sd-memory-cards-logo.png","contentUrl":"https:\/\/sd-memory-cards.net\/wp-content\/uploads\/2022\/11\/sd-memory-cards-logo.png","width":748,"height":148,"caption":"SD Memory Cards"},"image":{"@id":"https:\/\/sd-memory-cards.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100068407795273"]},{"@type":"Person","@id":"https:\/\/sd-memory-cards.net\/#\/schema\/person\/c682d19e914a27e7ad753c9a4dd6af17","name":"SD Team","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/92c1bed94f5f72dd3a74aed94c1ef7f6a4fff2af9bcf7471e9124be460526205?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92c1bed94f5f72dd3a74aed94c1ef7f6a4fff2af9bcf7471e9124be460526205?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92c1bed94f5f72dd3a74aed94c1ef7f6a4fff2af9bcf7471e9124be460526205?s=96&d=mm&r=g","caption":"SD Team"},"url":"https:\/\/sd-memory-cards.net\/it\/author\/sd-team\/"},false]},"og_video":"https:\/\/www.youtube.com\/embed\/DyF4qdgd3bY","og_video_type":"text\/html","og_video_duration":"155","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_upload_date":"2020-08-05T09:00:36+00:00","ya_ovs_allow_embed":"true"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":3},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/posts\/15369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/users\/939"}],"replies":[{"embeddable":true,"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/comments?post=15369"}],"version-history":[{"count":0,"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/posts\/15369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/media\/16129"}],"wp:attachment":[{"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/media?parent=15369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/categories?post=15369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sd-memory-cards.net\/it\/wp-json\/wp\/v2\/tags?post=15369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}